{"id":878,"date":"2019-12-12T12:25:59","date_gmt":"2019-12-12T12:25:59","guid":{"rendered":"https:\/\/elcravatte.com\/?post_type=shops&#038;p=878"},"modified":"2019-12-16T13:24:15","modified_gmt":"2019-12-16T13:24:15","slug":"hosentraegerspezialist-at","status":"publish","type":"shops","link":"https:\/\/elcravatte.com\/en\/shops\/hosentraegerspezialist-at\/","title":{"rendered":"Hosentraegerspezialist.at"},"content":{"rendered":"<div id=\"themify_builder_content-878\" data-postid=\"878\" class=\"themify_builder_content themify_builder_content-878 themify_builder\">\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":879,"parent":0,"menu_order":0,"template":"","meta":[],"categories":[1],"tags":[42],"builder_content":"","ptb_metabox":{"ptb_merken_tekst":"Hosentr\u00e4ger kaufen: einfach online","ptb_merken_logo":{"1":"https:\/\/elcravatte.com\/wp-content\/uploads\/2019\/12\/hosentraegerspezialist-at.png","2":"https:\/\/www.hosentraegerspezialist.at\/"},"ptb_merken_omschrijving":"Entdecken Sie unser Assortiment Herrenhosentr\u00e4ger und w\u00e4hlen Sie Ihr Lieblingsst\u00fcck aus! Bei uns finden Sie die passenden Hosentr\u00e4ger f\u00fcr M\u00e4nner f\u00fcr jede Gelegenheit und zu jedem Anzug. ","ptb_shops_email":"info@accessoirespezialist.at","ptb_shops_ga_naar":["shop","https:\/\/www.hosentraegerspezialist.at\/"]},"ptb_taxonomy":{"category":[{"term_id":1,"name":"accessoires","slug":"uncategorized","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":67,"filter":"raw"}],"post_tag":[{"term_id":42,"name":"bretels","slug":"bretels","term_group":0,"term_taxonomy_id":42,"taxonomy":"post_tag","description":"","parent":0,"count":12,"filter":"raw"}],"landen":[{"term_id":50,"name":"Oostenrijk","slug":"oostenrijk","term_group":0,"term_taxonomy_id":50,"taxonomy":"landen","description":"","parent":0,"count":7,"filter":"raw"}]},"ptb_featured_image":{"url":"https:\/\/elcravatte.com\/wp-content\/uploads\/2019\/12\/hosentraegerspezialist-at.png","title":"hosentraegerspezialist-at","caption":""},"_links":{"self":[{"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/shops\/878"}],"collection":[{"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/shops"}],"about":[{"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/types\/shops"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/media\/879"}],"wp:attachment":[{"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcravatte.com\/en\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}